{"id":531,"date":"2021-07-02T03:46:25","date_gmt":"2021-07-02T03:46:25","guid":{"rendered":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/?page_id=531"},"modified":"2026-03-19T04:41:35","modified_gmt":"2026-03-19T04:41:35","slug":"%e0%b8%95%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b9%80%e0%b8%a3%e0%b8%b2","status":"publish","type":"page","link":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/%e0%b8%95%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b9%80%e0%b8%a3%e0%b8%b2\/","title":{"rendered":"\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32"},"content":{"rendered":"<h1 style=\"text-align: center;\">\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23 053 94 4808<br \/>\n\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 053 94 4808<br \/>\n\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 053 94 4830<\/h1>\n<hr \/>\n<h1 style=\"text-align: center;\">\u0e04\u0e13\u0e30\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<br \/>\n239 \u0e16.\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e15.\u0e2a\u0e38\u0e40\u0e17\u0e1e \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 50200<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23 053 94 4808 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 053 94 4808 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 053 94 4830 \u0e04\u0e13\u0e30\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 239 \u0e16.\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e15.\u0e2a\u0e38\u0e40\u0e17\u0e1e \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 50200<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/pages\/531"}],"collection":[{"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/comments?post=531"}],"version-history":[{"count":5,"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/pages\/531\/revisions"}],"predecessor-version":[{"id":759,"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/pages\/531\/revisions\/759"}],"wp:attachment":[{"href":"https:\/\/www.finearts.cmu.ac.th\/administrative-offices\/wp-json\/wp\/v2\/media?parent=531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}